{"id":4671,"date":"2020-09-08T10:29:35","date_gmt":"2020-09-08T02:29:35","guid":{"rendered":"https:\/\/musicchildren.org.hk\/?page_id=4671"},"modified":"2020-10-22T18:24:49","modified_gmt":"2020-10-22T10:24:49","slug":"cradle-tutor","status":"publish","type":"page","link":"https:\/\/musicchildren.org.hk\/en\/about\/team\/music-team\/cradle-tutor\/","title":{"rendered":"Cradle Tutor"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":3584,"menu_order":105,"comment_status":"closed","ping_status":"closed","template":"page-choir-tutor.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4671","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/pages\/4671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/comments?post=4671"}],"version-history":[{"count":12,"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/pages\/4671\/revisions"}],"predecessor-version":[{"id":5855,"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/pages\/4671\/revisions\/5855"}],"up":[{"embeddable":true,"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/pages\/3584"}],"wp:attachment":[{"href":"https:\/\/musicchildren.org.hk\/en\/wp-json\/wp\/v2\/media?parent=4671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}